{"id":6720,"date":"2025-11-18T09:33:48","date_gmt":"2025-11-18T08:33:48","guid":{"rendered":"https:\/\/dev.visitbratislava.com\/events\/stlp-marca-aurelia-a-slovensko-2\/"},"modified":"2025-11-18T09:33:48","modified_gmt":"2025-11-18T08:33:48","slug":"stlp-marca-aurelia-a-slovensko-2","status":"publish","type":"events","link":"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/","title":{"rendered":"St\u013ap Marca Aurelia a Slovensko"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":6718,"menu_order":0,"template":"","events_category":[352],"price":[],"accesibility":[],"region":[],"class_list":["post-6720","events","type-events","status-publish","has-post-thumbnail","hentry","events_category-dauerausstellungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>St\u013ap Marca Aurelia a Slovensko - Visit Bratislava<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"St\u013ap Marca Aurelia a Slovensko - Visit Bratislava\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Bratislava\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/events\\\/stlp-marca-aurelia-a-slovensko-2\\\/\",\"url\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/events\\\/stlp-marca-aurelia-a-slovensko-2\\\/\",\"name\":\"St\u013ap Marca Aurelia a Slovensko - Visit Bratislava\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/events\\\/stlp-marca-aurelia-a-slovensko-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/events\\\/stlp-marca-aurelia-a-slovensko-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.visitbratislava.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/1168102-383.jpg\",\"datePublished\":\"2025-11-18T08:33:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/events\\\/stlp-marca-aurelia-a-slovensko-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/events\\\/stlp-marca-aurelia-a-slovensko-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/events\\\/stlp-marca-aurelia-a-slovensko-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dev.visitbratislava.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/1168102-383.jpg\",\"contentUrl\":\"https:\\\/\\\/dev.visitbratislava.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/1168102-383.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/events\\\/stlp-marca-aurelia-a-slovensko-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"St\u013ap Marca Aurelia a Slovensko\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/\",\"name\":\"Visit Bratislava\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev.visitbratislava.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"St\u013ap Marca Aurelia a Slovensko - Visit Bratislava","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"St\u013ap Marca Aurelia a Slovensko - Visit Bratislava","og_url":"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/","og_site_name":"Visit Bratislava","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/","url":"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/","name":"St\u013ap Marca Aurelia a Slovensko - Visit Bratislava","isPartOf":{"@id":"https:\/\/dev.visitbratislava.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/#primaryimage"},"image":{"@id":"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.visitbratislava.com\/wp-content\/uploads\/2026\/08\/1168102-383.jpg","datePublished":"2025-11-18T08:33:48+00:00","breadcrumb":{"@id":"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/#primaryimage","url":"https:\/\/dev.visitbratislava.com\/wp-content\/uploads\/2026\/08\/1168102-383.jpg","contentUrl":"https:\/\/dev.visitbratislava.com\/wp-content\/uploads\/2026\/08\/1168102-383.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.visitbratislava.com\/de\/events\/stlp-marca-aurelia-a-slovensko-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.visitbratislava.com\/de\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/dev.visitbratislava.com\/de\/events\/"},{"@type":"ListItem","position":3,"name":"St\u013ap Marca Aurelia a Slovensko"}]},{"@type":"WebSite","@id":"https:\/\/dev.visitbratislava.com\/de\/#website","url":"https:\/\/dev.visitbratislava.com\/de\/","name":"Visit Bratislava","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.visitbratislava.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/events\/6720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/types\/events"}],"author":[{"embeddable":true,"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/media\/6718"}],"wp:attachment":[{"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/media?parent=6720"}],"wp:term":[{"taxonomy":"events_category","embeddable":true,"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/events_category?post=6720"},{"taxonomy":"price","embeddable":true,"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/price?post=6720"},{"taxonomy":"accesibility","embeddable":true,"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/accesibility?post=6720"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/dev.visitbratislava.com\/de\/wp-json\/wp\/v2\/region?post=6720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}